{"id":587,"date":"2016-09-12T16:55:39","date_gmt":"2016-09-12T20:55:39","guid":{"rendered":"http:\/\/simon.wps.dev\/fr\/sample-page\/"},"modified":"2018-10-15T19:44:59","modified_gmt":"2018-10-15T23:44:59","slug":"sample-page","status":"publish","type":"page","link":"https:\/\/gannademulder.com\/fr\/","title":{"rendered":"Welcome"},"content":{"rendered":"<div class=\"widget blue full\" id=\"sow-editor\" data-index=\"0\"><div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Il existe g\u00e9n\u00e9ralement deux fa\u00e7ons d'obtenir un pr\u00eat hypoth\u00e9caire au Canada : aupr\u00e8s d'une institution financi\u00e8re ou aupr\u00e8s d'un courtier hypoth\u00e9caire.<\/p>\n<p>Alors qu'une institution financi\u00e8re offre uniquement des produits qui lui sont propres, les courtiers hypoth\u00e9caires autoris\u00e9s acheminent chaque ann\u00e9e des millions de dollars en cr\u00e9dit hypoth\u00e9caire vers les plus grandes banques, coop\u00e9ratives de cr\u00e9dit, soci\u00e9t\u00e9s de fiducie et institutions financi\u00e8res du Canada. Ils offrent \u00e0 leurs clients un meilleur choix et un meilleur acc\u00e8s \u00e0 des centaines de produits hypoth\u00e9caires! Ces derniers peuvent donc avoir la certitude de b\u00e9n\u00e9ficier, en toute s\u00e9curit\u00e9, du meilleur pr\u00eat hypoth\u00e9caire r\u00e9pondant \u00e0 leurs besoins!<\/p>\n<p>Que vous soyez l'acheteur d'une premi\u00e8re maison, que vous d\u00e9siriez emprunter sur la valeur nette de votre propri\u00e9t\u00e9 (votre avoir propre foncier) \u00e0 des fins d'investissement ou de loisir, ou que votre hypoth\u00e8que actuelle arrive simplement \u00e0 expiration, il vous faut prendre une d\u00e9cision \u00e9clair\u00e9e aupr\u00e8s d'un conseiller impartial.<\/p>\n<\/div>\n<\/div><\/div><div class=\"widget blue full\" id=\"autopilotmedia\" data-index=\"1\">\t\t    <div class=\"content video-container\" style=\"margin:0px;padding:0px;\">\n\t\t\t<iframe src=\"https:\/\/www.youtube.com\/embed\/T-7Ag9O1to0?rel=0\" frameborder=\"0\" allowfullscreen><\/iframe>\n                    <\/div>\n\n               <\/div><div class=\"widget blue half\" id=\"free-mortgage\" data-index=\"2\"><div class=\"column\">\n    <div class=\"header\">\n\t<div class=\"free-mortgage-icon\"><\/div>\n\t<h2><strong>Examen<\/strong> hypoth\u00e9caire gratuit<\/h2>\n\t<p>D\u00e9couvrez combien vaut votre propri\u00e9t\u00e9.<\/p>\n    <\/div>\n    <div class=\"form\">\n        <div class='gf_browser_gecko gform_wrapper' id='gform_wrapper_4385' >\n            <form method='post' enctype='multipart\/form-data' id='gform_4385' action='' data-ajax=\"true\">\n\n                <input name=\"id_number\" class=\"id_number\" value=\"4385\" type=\"hidden\">\n\n                <div style=\"display:none\" class=\"validation_error\">Un probl\u00e8me est survenu relativement \u00e0 votre soumission. Les erreurs ont \u00e9t\u00e9 soulign\u00e9es ci-dessous.<\/div>\n\n                <div class='gform_body'>\n                    <ul id='gform_fields_4385' class='gform_fields top_label form_sublabel_below description_below'>\n                        <li id='field_4385_name' class='gfield field_sublabel_below field_description_below'>\n                            <div class='ginput_container'>\n                                <input name='name' id='name_4385' type='text' class='large'  tabindex='1'  placeholder='Pr\u00e9nom' \/>\n                            <\/div>\n                            <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                        <\/li>\n                        <li id='field_4385_phone' class='gfield field_sublabel_below field_description_below' >\n                            <div class='ginput_container'>\n                                <input name='phone' id='phone_4385' type='text' class='large' tabindex='2'  placeholder='T\u00e9l\u00e9phone' \/>\n                            <\/div>\n                            <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                        <\/li>\n                        <li id='field_4385_amount' class='gfield field_sublabel_below field_description_below' >\n                            <div class='ginput_container'>\n                                <input name='amount' id='amount_4385' type='text' class='large' tabindex='2'  placeholder='Montant du pr\u00eat hypoth\u00e9caire' \/>\n                            <\/div>\n                            <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                        <\/li>\n                        <li id='field_4385_renewal' class='gfield field_sublabel_below field_description_below' >\n                            <div class='ginput_container'>\n                                <input name='renewal' id='renewal_4385' type='text' class='large' tabindex='2'  placeholder='Date du renouvellement' \/>\n                            <\/div>\n                            <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                        <\/li>\n                        <li id='field_4385_day' class='gfield field_sublabel_below field_description_below' >\n                            <div class='ginput_container'>\n                                <select name='day' id='day_4385'  class='large gfield_select' tabindex='3' >\n                                    <option value='' class='gf_placeholder'>Meilleur jour pour l'appel<\/option>\n                                    <option value='Saturday'>samedi<\/option>\n                                    <option value='Sunday'>dimanche<\/option>\n                                    <option value='Monday'>lundi<\/option>\n                                    <option value='Tuesday'>mardi<\/option>\n                                    <option value='Wednesday'>mercredi<\/option>\n                                    <option value='Thursday'>jeudi<\/option>\n                                    <option value='Friday'>vendredi<\/option>\n                                <\/select>\n                            <\/div>\n                            <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                        <\/li>\n                        <li id='field_4385_time' class='gfield field_sublabel_below field_description_below' >\n                            <div class='ginput_container'>\n                                <input name='time' id='time_4385' type='text' class='large'  tabindex='4'  placeholder='Meilleure heure pour l'appel' \/>\n                            <\/div>\n                            <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                        <\/li>\n                        <li id='field_4385_g-recaptcha-response' class='gfield field_sublabel_below field_description_below'>\n                                                    <div class='ginput_container'>\n                                                            <div class=\"g-recaptcha\" id=\"widget-2-0-0\" style=\"transform:scale(0.6);-webkit-transform:scale(0.6);transform-origin:0 0;-webkit-transform-origin:0 0;\"><\/div>\n                                                    <\/div>\n                                                    <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                                            <\/li>\n                    <\/ul>\n                <\/div>\n\n                <div class='gform_footer top_label'>\n                    <input type='submit' id='gform_submit_button_4385' class='gform_button button mortgage_review_submit' value='Je veux ma maison de r\u00eave!' tabindex='5'>\n                <\/div>\n                            <div class='loading'><\/div>\n            <\/form>\n        <\/div>\n    <\/div>\n\t\n\t<div style=\"display:none\" id=\"mortgage_review_4385_confirmation_message\" class=\"gforms_confirmation_message\">\n\t\t<div class=\"gform_confirmation_wrapper\">\n\t\t\t<div class=\"gform_confirmation_message\">\n\t\t\t\t<p>Merci d\u2019avoir communiqu\u00e9 avec nous! Nous communiquerons avec vous sous peu.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n\n<\/div><div class=\"widget blue half\" id=\"calculators\" data-index=\"3\">\n\n\t\t\t\t\n\t\t\t\t<div class=\"content\">\n\t\t\t\t\t<h2>Nos calculatrices vous permettront d\u2019explorer vos options en mati\u00e8re de pr\u00eats hypoth\u00e9caires.<\/h2>\n\t\t\t\t\t<a class=\"buttons\" href=\"https:\/\/gannademulder.com\/refinance\/refinance-calculators\/\">Cela m\u2019int\u00e9resse!<\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div><div class=\"widget blue half\" id=\"videos\" data-index=\"4\">        <div >\r\n            <h2>Videos<\/h2>\r\n            <div id=\"custom-sliders\" class=\"owl-carousel videos\">\r\n                \r\n                                        <div class=\"item\">\r\n                        <div class=\"content\">\r\n                            <!-- (1) video wrapper -->\r\n                            <div class=\"youtube\" data-embed=\"\">\r\n                                <!-- (2) the \"play\" button -->\r\n                                <div class=\"play-button\"><\/div>\r\n                            <\/div>\r\n                            <p><\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n\r\n                \r\n                                        <div class=\"item\">\r\n                        <div class=\"content\">\r\n                            <!-- (1) video wrapper -->\r\n                            <div class=\"youtube\" data-embed=\"\">\r\n                                <!-- (2) the \"play\" button -->\r\n                                <div class=\"play-button\"><\/div>\r\n                            <\/div>\r\n                            <p><\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n\r\n                \r\n                                        <div class=\"item\">\r\n                        <div class=\"content\">\r\n                            <!-- (1) video wrapper -->\r\n                            <div class=\"youtube\" data-embed=\"\">\r\n                                <!-- (2) the \"play\" button -->\r\n                                <div class=\"play-button\"><\/div>\r\n                            <\/div>\r\n                            <p><\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n\r\n                \r\n                                        <div class=\"item\">\r\n                        <div class=\"content\">\r\n                            <!-- (1) video wrapper -->\r\n                            <div class=\"youtube\" data-embed=\"\">\r\n                                <!-- (2) the \"play\" button -->\r\n                                <div class=\"play-button\"><\/div>\r\n                            <\/div>\r\n                            <p><\/p>\r\n                        <\/div>\r\n                    <\/div>\r\n\r\n                            <\/div>\r\n        <\/div>\r\n        <\/div><div class=\"widget blue half\" id=\"request-call\" data-index=\"5\"><div class=\"column\">\n    <h2>Demande de Rappel<\/h2>\n    <h3>Remplissez le questionnaire ci-dessous et un courtier vous <b>appellera selon vos disponibilites.<\/b><\/h3>\n\n    <div class='gf_browser_gecko gform_wrapper' id='gform_wrapper_4924' >\n        <form method='post' enctype='multipart\/form-data' id='gform_4924' action='' data-ajax=\"true\">\n            \n            <input name=\"id_number\" class=\"id_number\" value=\"4924\" type=\"hidden\">\n            \n            <div style=\"display:none\" class=\"validation_error\">There was a problem with your submission. Errors have been highlighted below.<\/div>\n\t\t\t\t    \n            <div class='gform_body'>\n                <ul id='gform_fields_4924' class='gform_fields top_label form_sublabel_below description_below'>\n                    <li id='field_4924_name' class='gfield field_sublabel_below field_description_below'>\n                        <div class='ginput_container'>\n                            <input name='name' id='name_4924' type='text' class='large'  tabindex='1'  placeholder='Pr\u00e9nom' \/>\n                        <\/div>\n                        <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                    <\/li>\n                    <li id='field_4924_phone' class='gfield field_sublabel_below field_description_below' >\n                        <div class='ginput_container'>\n                            <input name='phone' id='phone_4924' type='text' class='large' tabindex='2'  placeholder='T\u00e9l\u00e9phone' \/>\n                        <\/div>\n                        <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                    <\/li>\n                    <li id='field_4924_day' class='gfield field_sublabel_below field_description_below' >\n                        <div class='ginput_container'>\n                            <select name='day' id='day_4924'  class='large gfield_select' tabindex='3' >\n                                <option value='' class='gf_placeholder'>Meilleur jour pour l'appel<\/option>\n                                <option value='Saturday'>samedi<\/option>\n                                <option value='Sunday'>dimanche<\/option>\n                                <option value='Monday'>lundi<\/option>\n                                <option value='Tuesday'>mardi<\/option>\n                                <option value='Wednesday'>mercredi<\/option>\n                                <option value='Thursday'>jeudi<\/option>\n                                <option value='Friday'>vendredi<\/option>\n                            <\/select>\n                        <\/div>\n                        <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                    <\/li>\n                    <li id='field_4924_time' class='gfield field_sublabel_below field_description_below' >\n                        <div class='ginput_container'>\n                            <input name='time' id='time_4924' type='text' class='large'  tabindex='4'  placeholder='Meilleure heure pour l\u2019appel' \/>\n                        <\/div>\n                        <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                    <\/li>\n                    <li id='field_4924_g-recaptcha-response' class='gfield field_sublabel_below field_description_below'>\n\t\t\t\t\t\t<div class='ginput_container'>\n\t\t\t\t\t\t\t<div class=\"g-recaptcha\" id=\"widget-3-1-0\" style=\"transform:scale(0.6);-webkit-transform:scale(0.6);transform-origin:0 0;-webkit-transform-origin:0 0;\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n\t\t\t\t\t<\/li>\n                <\/ul>\n            <\/div>\n\n            <div class='gform_footer top_label'>\n                <input type='submit' id='gform_submit_button_4924' class='gform_button button requestacall_submit' value='Rappellez-moi' tabindex='5'>\n            <\/div>\n\t\t\t<div class='loading'><\/div>\n        <\/form>\n    <\/div>\n\t\n\t<div style=\"display:none\" id=\"requestacall_4924_confirmation_message\" class=\"gforms_confirmation_message\">\n\t\t<div class=\"gform_confirmation_wrapper\">\n\t\t\t<div class=\"gform_confirmation_message\">\n\t\t\t\t<p>Merci d\u00e2\u0080\u0099avoir communiqu\u00c3\u00a9 avec nous! Nous communiquerons avec vous sous peu.<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n\n\n\n\n<\/div><div class=\"widget blue full\" id=\"newsletter\" data-index=\"6\">\n<div class=\"header\">\n    <div class=\"newsletter-image\">\n    <\/div>\n    <h2>Tenez-vous au courant des nouvelles les plus <span>r\u00e9centes en mati\u00e8re de pr\u00eats hypoth\u00e9caires<\/span><\/h2>\n<\/div>\n<div class=\"form\">\n    <p>Abonnez-vous \u00e0 notre bulletin<\/p>\n    <div class=\"gf_browser_gecko gform_wrapper gform_validation_error\" id=\"gform_wrapper_2616\">\n        <form method=\"post\" enctype=\"multipart\/form-data\" id=\"gform_2616\" action=\"\">\n\n            <input name=\"id_number\" class=\"id_number\" value=\"2616\" type=\"hidden\">\n\n            <div style=\"display:none\" class=\"validation_error\">Un probl\u00e8me est survenu relativement \u00e0 votre soumission. Les erreurs ont \u00e9t\u00e9 soulign\u00e9es ci-dessous.<\/div>\n            <div class=\"gform_body\">\n                <ul id=\"gform_fields_2616\" class=\"gform_fields top_label form_sublabel_below description_below\">\n                    <li id=\"field_2616_name\" class=\"gfield gf_left_half field_sublabel_below field_description_below\">\n                        <div class=\"ginput_container ginput_container_text\">\n                            <input name=\"name\" id=\"name_2616\" value=\"\" class=\"large\" placeholder=\"Pr\u00e9nom\" type=\"text\">\n                        <\/div>\n                        <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                    <\/li><li id=\"field_2616_lastname\" class=\"gfield gf_right_half field_sublabel_below field_description_below\">\n                        <div class=\"ginput_container ginput_container_lastname\">\n                            <input name=\"lastname\" id=\"lastname_2616\" value=\"\" class=\"medium\" placeholder=\"Nom de famille\" type=\"text\">\n                        <\/div>\n                        <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                    <\/li>\n                    <li id=\"field_2616_email\" class=\"gfield field_sublabel_below field_description_below\">\n                        <div class=\"ginput_container ginput_container_email\">\n                            <input name=\"email\" id=\"email_2616\" value=\"\" class=\"large\" placeholder=\"Courriel\" type=\"text\">\n                        <\/div>\n                        <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                    <\/li>\n                    <li id=\"field_2616_newsletter_list\" class=\"gfield field_sublabel_below field_description_below newsletter_checkbox\">\n                        <input name=\"newsletter_list\" value=\"Yes\" id=\"newsletter_list_2616\" type=\"checkbox\">\n                        <label id=\"newsletter_list_label\"><b>Liste des personnes abonn\u00e9es au bulletin:<\/b> Nouvelles du march\u00e9, conseils et renseignements opportuns \u00e0 l\u2019intention des acheteurs et des vendeurs.<\/label>\n                        <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                    <\/li>\n                    <li id=\"field_2616_newsletter_weekly\" class=\"gfield field_sublabel_below field_description_below newsletter_checkbox\">\n                        <input name=\"newsletter_weekly\" value=\"Yes\" id=\"newsletter_weekly_2616\" type=\"checkbox\">\n                        <label id=\"newsletter_list_label\"><b>Rappel hebdomadaire des taux:<\/b> Taux \u00e0 jour envoy\u00e9s dans votre bo\u00eete de r\u00e9ception tous les lundis matin.<\/label>\n                        <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                    <\/li>\n\n\n                    <li id='field_2616_g-recaptcha-response' class='gfield field_sublabel_below field_description_below'>\n                        <div class='ginput_container'>\n                            <div class=\"g-recaptcha\" id=\"widget-4-0-0\" style=\"transform:scale(0.6);-webkit-transform:scale(0.6);transform-origin:0 0;-webkit-transform-origin:0 0;\"><\/div>\n                        <\/div>\n                        <div style=\"display:none\" class=\"gfield_description validation_message\"><\/div>\n                    <\/li>\n                <\/ul>\n            <\/div>\n            <div class=\"gform_footer top_label\"> \n                <input id=\"gform_submit_button_2616\" class=\"gform_button button newsletter_submit\" value=\"Envoyez-moi les nouvelles!\" type=\"submit\"> \n            <\/div>\n            <div class='loading'><\/div>\n        <\/form>\n    <\/div>    \n\n\n    <div style=\"display:none\" id=\"newsletter_2616_confirmation_message\" class=\"gforms_confirmation_message\">\n        <div class=\"gform_confirmation_wrapper\">\n            <div class=\"gform_confirmation_message\">\n                <p>Merci d\u2019avoir communiqu\u00e9 avec nous! Nous communiquerons avec vous sous peu.<\/p>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<\/div>\n\n\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Il existe g\u00e9n\u00e9ralement deux fa\u00e7ons d&rsquo;obtenir un pr\u00eat hypoth\u00e9caire au Canada : aupr\u00e8s d&rsquo;une institution financi\u00e8re ou aupr\u00e8s d&rsquo;un courtier hypoth\u00e9caire. Alors qu&rsquo;une institution financi\u00e8re offre uniquement des produits qui lui sont propres, les courtiers hypoth\u00e9caires autoris\u00e9s acheminent chaque ann\u00e9e des millions de dollars en cr\u00e9dit hypoth\u00e9caire vers les plus grandes banques, coop\u00e9ratives de cr\u00e9dit, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"page-templates\/homepage.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gannademulder.com\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Welcome - Centres Hypoth\u00e9caires Dominion\" \/>\n<meta property=\"og:description\" content=\"Il existe g\u00e9n\u00e9ralement deux fa\u00e7ons d&#039;obtenir un pr\u00eat hypoth\u00e9caire au Canada : aupr\u00e8s d&#039;une institution financi\u00e8re ou aupr\u00e8s d&#039;un courtier hypoth\u00e9caire. Alors qu&#039;une institution financi\u00e8re offre uniquement des produits qui lui sont propres, les courtiers hypoth\u00e9caires autoris\u00e9s acheminent chaque ann\u00e9e des millions de dollars en cr\u00e9dit hypoth\u00e9caire vers les plus grandes banques, coop\u00e9ratives de cr\u00e9dit, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gannademulder.com\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Centres Hypoth\u00e9caires Dominion\" \/>\n<meta property=\"article:modified_time\" content=\"2018-10-15T23:44:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/gannademulder.com\/#organization\",\"name\":\"Centres Hypoth\\u00e9caires Dominion\",\"url\":\"https:\/\/gannademulder.com\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/gannademulder.com\/#logo\",\"inLanguage\":\"fr-FR\",\"url\":\"http:\/\/master.wps.dlcserver.com\/wp-content\/uploads\/2017\/01\/vector_DLC1.jpg\",\"contentUrl\":\"http:\/\/master.wps.dlcserver.com\/wp-content\/uploads\/2017\/01\/vector_DLC1.jpg\",\"width\":369,\"height\":173,\"caption\":\"Centres Hypoth\\u00e9caires Dominion\"},\"image\":{\"@id\":\"https:\/\/gannademulder.com\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/gannademulder.com\/#website\",\"url\":\"https:\/\/gannademulder.com\/\",\"name\":\"Centres Hypoth\\u00e9caires Dominion\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\/\/gannademulder.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/gannademulder.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/gannademulder.com\/fr\/#webpage\",\"url\":\"https:\/\/gannademulder.com\/fr\/\",\"name\":\"Welcome - Centres Hypoth\\u00e9caires Dominion\",\"isPartOf\":{\"@id\":\"https:\/\/gannademulder.com\/#website\"},\"datePublished\":\"2016-09-12T20:55:39+00:00\",\"dateModified\":\"2018-10-15T23:44:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/gannademulder.com\/fr\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/gannademulder.com\/fr\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/gannademulder.com\/fr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/gannademulder.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Welcome\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gannademulder.com\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Welcome - Centres Hypoth\u00e9caires Dominion","og_description":"Il existe g\u00e9n\u00e9ralement deux fa\u00e7ons d'obtenir un pr\u00eat hypoth\u00e9caire au Canada : aupr\u00e8s d'une institution financi\u00e8re ou aupr\u00e8s d'un courtier hypoth\u00e9caire. Alors qu'une institution financi\u00e8re offre uniquement des produits qui lui sont propres, les courtiers hypoth\u00e9caires autoris\u00e9s acheminent chaque ann\u00e9e des millions de dollars en cr\u00e9dit hypoth\u00e9caire vers les plus grandes banques, coop\u00e9ratives de cr\u00e9dit, [&hellip;]","og_url":"https:\/\/gannademulder.com\/fr\/","og_site_name":"Centres Hypoth\u00e9caires Dominion","article_modified_time":"2018-10-15T23:44:59+00:00","twitter_card":"summary","twitter_misc":{"Dur\u00e9e de lecture est.":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/gannademulder.com\/#organization","name":"Centres Hypoth\u00e9caires Dominion","url":"https:\/\/gannademulder.com\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/gannademulder.com\/#logo","inLanguage":"fr-FR","url":"http:\/\/master.wps.dlcserver.com\/wp-content\/uploads\/2017\/01\/vector_DLC1.jpg","contentUrl":"http:\/\/master.wps.dlcserver.com\/wp-content\/uploads\/2017\/01\/vector_DLC1.jpg","width":369,"height":173,"caption":"Centres Hypoth\u00e9caires Dominion"},"image":{"@id":"https:\/\/gannademulder.com\/#logo"}},{"@type":"WebSite","@id":"https:\/\/gannademulder.com\/#website","url":"https:\/\/gannademulder.com\/","name":"Centres Hypoth\u00e9caires Dominion","description":"Just another WordPress site","publisher":{"@id":"https:\/\/gannademulder.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gannademulder.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/gannademulder.com\/fr\/#webpage","url":"https:\/\/gannademulder.com\/fr\/","name":"Welcome - Centres Hypoth\u00e9caires Dominion","isPartOf":{"@id":"https:\/\/gannademulder.com\/#website"},"datePublished":"2016-09-12T20:55:39+00:00","dateModified":"2018-10-15T23:44:59+00:00","breadcrumb":{"@id":"https:\/\/gannademulder.com\/fr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gannademulder.com\/fr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/gannademulder.com\/fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gannademulder.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Welcome"}]}]}},"_links":{"self":[{"href":"https:\/\/gannademulder.com\/fr\/wp-json\/wp\/v2\/pages\/587"}],"collection":[{"href":"https:\/\/gannademulder.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gannademulder.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gannademulder.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gannademulder.com\/fr\/wp-json\/wp\/v2\/comments?post=587"}],"version-history":[{"count":27,"href":"https:\/\/gannademulder.com\/fr\/wp-json\/wp\/v2\/pages\/587\/revisions"}],"predecessor-version":[{"id":1294,"href":"https:\/\/gannademulder.com\/fr\/wp-json\/wp\/v2\/pages\/587\/revisions\/1294"}],"wp:attachment":[{"href":"https:\/\/gannademulder.com\/fr\/wp-json\/wp\/v2\/media?parent=587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}